{"id":7715,"date":"2025-09-11T18:48:39","date_gmt":"2025-09-11T16:48:39","guid":{"rendered":"https:\/\/guidogrohmann.de\/?page_id=7715"},"modified":"2025-10-09T09:36:05","modified_gmt":"2025-10-09T07:36:05","slug":"pforzheim-gallery","status":"publish","type":"page","link":"https:\/\/guidogrohmann.de\/en\/guido-galleries\/pforzheim-gallery\/","title":{"rendered":"Pforzheim"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"7715\" class=\"elementor elementor-7715\">\n\t\t\t\t\t\t<section class=\"jarallax lazyload elementor-section elementor-top-section elementor-element elementor-element-4fc0e89 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-jarallax=\"\" data-speed=\"0.75\" data-type=\"scroll\" data-parallax=\"scroll\" style=\"background-image:url(&quot;http:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/germany-pforzheim-02-guido-grohmann-2017-07.jpg&quot;);\" data-image-src=\"http:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/germany-pforzheim-02-guido-grohmann-2017-07.jpg\" data-id=\"4fc0e89\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d6b2319\" data-id=\"d6b2319\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d0780ed section-align-center section-size-large subtitle-style-default elementor-widget elementor-widget-section-heading\" data-id=\"d0780ed\" data-element_type=\"widget\" data-widget_type=\"section-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"section-heading headingstyle-subtitle\"><h5 class=\"entry-sub-title section-sub-title\">Gallery<\/h5><div class=\"section-title-wrapper\"><h2 class=\"entry-title section-title\">Pforzheim<\/h2><\/div><div class=\"section-description clearfix\"><div class=\"section-description-inner\"><p>Pforzheim - the city where I work - is a place where post-war urban grit, centuries of jewelry craft, and the timeless nature of the Black Forest intertwine.<\/p>\n<\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-75007df elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"75007df\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d5681e2\" data-id=\"d5681e2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6b86d2f elementor-widget elementor-widget-thumbnails-grid\" data-id=\"6b86d2f\" data-element_type=\"widget\" data-widget_type=\"thumbnails-grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"thumbnails-shortcode gridblock-columns-wrap grid-style-wall-spaced-wrap clearfix\"><div class=\"thumbnails-grid-container lightgallery-container grid-style-wall-spaced thumbnail-gutter-spaced    boxtitle-active gridblock-two  has-effect-zoom\"  data-columns=\"2\"><div class=\"gridblock-element  grid-animate-display-all isotope-displayed gridblock-thumbnail-id-7733 gridblock-col-1\"><div class=\"gridblock-ajax gridblock-grid-element gridblock-element-inner\" data-rel=\"7715\"><div class=\"gridblock-background-hover\"><a data-elementor-open-lightbox=\"no\" data-exthumbimage=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/germany-pforzheim-wallberg-02-guido-grohmann-2020-03-160x160.jpg\" class=\"lightbox-active lightbox-image gridblock-sole-link\" data-sub-html=\"&lt;div class=&quot;lightbox-text-wrap &quot;&gt;&lt;h4 class=&quot;lightbox-text lightbox-text-title&quot;&gt;Wallberg&lt;\/h4&gt;&lt;div class=&quot;lightbox-text entry-content&quot;&gt;The Wallberg stands as a silent witness to Pforzheim\u2019s destruction and rebirth.&lt;\/div&gt;&lt;\/div&gt;\" href=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/germany-pforzheim-wallberg-02-guido-grohmann-2020-03.jpg\" data-src=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/germany-pforzheim-wallberg-02-guido-grohmann-2020-03.jpg\"><div class=\"gridblock-links-wrap\"><\/div><div class=\"boxtitle-hover\"><div class=\"work-details\"><h4>Wallberg<\/h4><p class=\"entry-content work-description\">The Wallberg stands as a silent witness to Pforzheim\u2019s destruction and rebirth.<\/p><\/div><\/div><\/a><\/div><img decoding=\"async\" class=\"preload-image lazyload displayed-image\" src=\"https:\/\/guidogrohmann.de\/wp-content\/themes\/blacksilver\/images\/placeholders\/placeholder-770x770.gif\" data-src=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/germany-pforzheim-wallberg-02-guido-grohmann-2020-03-770x770.jpg\" alt=\"Wallberg\"><\/div><\/div><div class=\"gridblock-element  grid-animate-display-all isotope-displayed gridblock-thumbnail-id-8402 gridblock-col-2\"><div class=\"gridblock-ajax gridblock-grid-element gridblock-element-inner\" data-rel=\"7715\"><div class=\"gridblock-background-hover\"><a data-elementor-open-lightbox=\"no\" data-exthumbimage=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/20250920-guido-grohmann-pfozheim-wallberg-01-160x160.jpg\" class=\"lightbox-active lightbox-image gridblock-sole-link\" data-sub-html=\"&lt;div class=&quot;lightbox-text-wrap &quot;&gt;&lt;h4 class=&quot;lightbox-text lightbox-text-title&quot;&gt;Wallberg&lt;\/h4&gt;&lt;div class=&quot;lightbox-text entry-content&quot;&gt;The Wallberg stands as a silent witness to Pforzheim\u2019s destruction and rebirth.&lt;\/div&gt;&lt;\/div&gt;\" href=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/20250920-guido-grohmann-pfozheim-wallberg-01.jpg\" data-src=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/20250920-guido-grohmann-pfozheim-wallberg-01.jpg\"><div class=\"gridblock-links-wrap\"><\/div><div class=\"boxtitle-hover\"><div class=\"work-details\"><h4>Wallberg<\/h4><p class=\"entry-content work-description\">The Wallberg stands as a silent witness to Pforzheim\u2019s destruction and rebirth.<\/p><\/div><\/div><\/a><\/div><img decoding=\"async\" class=\"preload-image lazyload displayed-image\" src=\"https:\/\/guidogrohmann.de\/wp-content\/themes\/blacksilver\/images\/placeholders\/placeholder-770x770.gif\" data-src=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/20250920-guido-grohmann-pfozheim-wallberg-01-770x770.jpg\" alt=\"Wallberg\"><\/div><\/div><div class=\"gridblock-element  grid-animate-display-all isotope-displayed gridblock-thumbnail-id-8398 gridblock-col-1\"><div class=\"gridblock-ajax gridblock-grid-element gridblock-element-inner\" data-rel=\"7715\"><div class=\"gridblock-background-hover\"><a data-elementor-open-lightbox=\"no\" data-exthumbimage=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/20250920-guido-grohmann-pfozheim-wallberg-02-160x160.jpg\" class=\"lightbox-active lightbox-image gridblock-sole-link\" data-sub-html=\"&lt;div class=&quot;lightbox-text-wrap &quot;&gt;&lt;h4 class=&quot;lightbox-text lightbox-text-title&quot;&gt;Wallberg&lt;\/h4&gt;&lt;div class=&quot;lightbox-text entry-content&quot;&gt;The Wallberg stands as a silent witness to Pforzheim\u2019s destruction and rebirth.&lt;\/div&gt;&lt;\/div&gt;\" href=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/20250920-guido-grohmann-pfozheim-wallberg-02.jpg\" data-src=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/20250920-guido-grohmann-pfozheim-wallberg-02.jpg\"><div class=\"gridblock-links-wrap\"><\/div><div class=\"boxtitle-hover\"><div class=\"work-details\"><h4>Wallberg<\/h4><p class=\"entry-content work-description\">The Wallberg stands as a silent witness to Pforzheim\u2019s destruction and rebirth.<\/p><\/div><\/div><\/a><\/div><img decoding=\"async\" class=\"preload-image lazyload displayed-image\" src=\"https:\/\/guidogrohmann.de\/wp-content\/themes\/blacksilver\/images\/placeholders\/placeholder-770x770.gif\" data-src=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/20250920-guido-grohmann-pfozheim-wallberg-02-770x770.jpg\" alt=\"Wallberg\"><\/div><\/div><div class=\"gridblock-element  grid-animate-display-all isotope-displayed gridblock-thumbnail-id-8396 gridblock-col-2\"><div class=\"gridblock-ajax gridblock-grid-element gridblock-element-inner\" data-rel=\"7715\"><div class=\"gridblock-background-hover\"><a data-elementor-open-lightbox=\"no\" data-exthumbimage=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/20250920-guido-grohmann-pfozheim-wallberg-03-160x160.jpg\" class=\"lightbox-active lightbox-image gridblock-sole-link\" data-sub-html=\"&lt;div class=&quot;lightbox-text-wrap &quot;&gt;&lt;h4 class=&quot;lightbox-text lightbox-text-title&quot;&gt;Wallberg&lt;\/h4&gt;&lt;div class=&quot;lightbox-text entry-content&quot;&gt;The Wallberg stands as a silent witness to Pforzheim\u2019s destruction and rebirth.&lt;\/div&gt;&lt;\/div&gt;\" href=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/20250920-guido-grohmann-pfozheim-wallberg-03.jpg\" data-src=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/20250920-guido-grohmann-pfozheim-wallberg-03.jpg\"><div class=\"gridblock-links-wrap\"><\/div><div class=\"boxtitle-hover\"><div class=\"work-details\"><h4>Wallberg<\/h4><p class=\"entry-content work-description\">The Wallberg stands as a silent witness to Pforzheim\u2019s destruction and rebirth.<\/p><\/div><\/div><\/a><\/div><img decoding=\"async\" class=\"preload-image lazyload displayed-image\" src=\"https:\/\/guidogrohmann.de\/wp-content\/themes\/blacksilver\/images\/placeholders\/placeholder-770x770.gif\" data-src=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/20250920-guido-grohmann-pfozheim-wallberg-03-770x770.jpg\" alt=\"Wallberg\"><\/div><\/div><div class=\"gridblock-element  grid-animate-display-all isotope-displayed gridblock-thumbnail-id-7717 gridblock-col-1\"><div class=\"gridblock-ajax gridblock-grid-element gridblock-element-inner\" data-rel=\"7715\"><div class=\"gridblock-background-hover\"><a data-elementor-open-lightbox=\"no\" data-exthumbimage=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/germany-pforzheim-01-guido-grohmann-2017-07-160x160.jpg\" class=\"lightbox-active lightbox-image gridblock-sole-link\" data-sub-html=\"&lt;div class=&quot;lightbox-text-wrap &quot;&gt;&lt;h4 class=&quot;lightbox-text lightbox-text-title&quot;&gt;Hafnerwiesen&lt;\/h4&gt;&lt;div class=&quot;lightbox-text entry-content&quot;&gt;The Hafnerwiesen unfold as Pforzheim\u2019s green retreat along the river, where nature softens the city\u2019s edge.&lt;\/div&gt;&lt;\/div&gt;\" href=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/germany-pforzheim-01-guido-grohmann-2017-07.jpg\" data-src=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/germany-pforzheim-01-guido-grohmann-2017-07.jpg\"><div class=\"gridblock-links-wrap\"><\/div><div class=\"boxtitle-hover\"><div class=\"work-details\"><h4>Hafnerwiesen<\/h4><p class=\"entry-content work-description\">The Hafnerwiesen unfold as Pforzheim\u2019s green retreat along the river, where nature softens the city\u2019s edge.<\/p><\/div><\/div><\/a><\/div><img decoding=\"async\" class=\"preload-image lazyload displayed-image\" src=\"https:\/\/guidogrohmann.de\/wp-content\/themes\/blacksilver\/images\/placeholders\/placeholder-770x770.gif\" data-src=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/germany-pforzheim-01-guido-grohmann-2017-07-770x770.jpg\" alt=\"Hafnerwiesen\"><\/div><\/div><div class=\"gridblock-element  grid-animate-display-all isotope-displayed gridblock-thumbnail-id-8401 gridblock-col-2\"><div class=\"gridblock-ajax gridblock-grid-element gridblock-element-inner\" data-rel=\"7715\"><div class=\"gridblock-background-hover\"><a data-elementor-open-lightbox=\"no\" data-exthumbimage=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/20250920-guido-grohmann-pforzheim-01-160x160.jpg\" class=\"lightbox-active lightbox-image gridblock-sole-link\" data-sub-html=\"&lt;div class=&quot;lightbox-text-wrap &quot;&gt;&lt;h4 class=&quot;lightbox-text lightbox-text-title&quot;&gt;The Tower&lt;\/h4&gt;&lt;div class=&quot;lightbox-text entry-content&quot;&gt;Sparkassen Tower and Turmquartier&lt;\/div&gt;&lt;\/div&gt;\" href=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/20250920-guido-grohmann-pforzheim-01.jpg\" data-src=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/20250920-guido-grohmann-pforzheim-01.jpg\"><div class=\"gridblock-links-wrap\"><\/div><div class=\"boxtitle-hover\"><div class=\"work-details\"><h4>The Tower<\/h4><p class=\"entry-content work-description\">Sparkassen Tower and Turmquartier<\/p><\/div><\/div><\/a><\/div><img decoding=\"async\" class=\"preload-image lazyload displayed-image\" src=\"https:\/\/guidogrohmann.de\/wp-content\/themes\/blacksilver\/images\/placeholders\/placeholder-770x770.gif\" data-src=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/20250920-guido-grohmann-pforzheim-01-770x770.jpg\" alt=\"The Tower\"><\/div><\/div><div class=\"gridblock-element  grid-animate-display-all isotope-displayed gridblock-thumbnail-id-8433 gridblock-col-1\"><div class=\"gridblock-ajax gridblock-grid-element gridblock-element-inner\" data-rel=\"7715\"><div class=\"gridblock-background-hover\"><a data-elementor-open-lightbox=\"no\" data-exthumbimage=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/guido-grohmann-pforzheim-kollmar-jordan-haus-01-web-160x160.jpg\" class=\"lightbox-active lightbox-image gridblock-sole-link\" data-sub-html=\"&lt;div class=&quot;lightbox-text-wrap &quot;&gt;&lt;h4 class=&quot;lightbox-text lightbox-text-title&quot;&gt;Kollmar &amp; Jordan House&lt;\/h4&gt;&lt;div class=&quot;lightbox-text entry-content&quot;&gt;Pforzheim&#039;s Technical Museum of the jewelry and watch industry&lt;\/div&gt;&lt;\/div&gt;\" href=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/guido-grohmann-pforzheim-kollmar-jordan-haus-01-web.jpg\" data-src=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/guido-grohmann-pforzheim-kollmar-jordan-haus-01-web.jpg\"><div class=\"gridblock-links-wrap\"><\/div><div class=\"boxtitle-hover\"><div class=\"work-details\"><h4>Kollmar & Jordan House<\/h4><p class=\"entry-content work-description\">Pforzheim's Technical Museum of the jewelry and watch industry<\/p><\/div><\/div><\/a><\/div><img decoding=\"async\" class=\"preload-image lazyload displayed-image\" src=\"https:\/\/guidogrohmann.de\/wp-content\/themes\/blacksilver\/images\/placeholders\/placeholder-770x770.gif\" data-src=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/guido-grohmann-pforzheim-kollmar-jordan-haus-01-web-770x770.jpg\" alt=\"Kollmar & Jordan House\"><\/div><\/div><div class=\"gridblock-element  grid-animate-display-all isotope-displayed gridblock-thumbnail-id-8436 gridblock-col-2\"><div class=\"gridblock-ajax gridblock-grid-element gridblock-element-inner\" data-rel=\"7715\"><div class=\"gridblock-background-hover\"><a data-elementor-open-lightbox=\"no\" data-exthumbimage=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/guido-grohmann-pforzheim-kollmar-jordan-haus-04-web-160x160.jpg\" class=\"lightbox-active lightbox-image gridblock-sole-link\" data-sub-html=\"&lt;div class=&quot;lightbox-text-wrap &quot;&gt;&lt;h4 class=&quot;lightbox-text lightbox-text-title&quot;&gt;Kollmar &amp; Jordan House&lt;\/h4&gt;&lt;div class=&quot;lightbox-text entry-content&quot;&gt;Pforzheim&#039;s Technical Museum of the jewelry and watch industry&lt;\/div&gt;&lt;\/div&gt;\" href=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/guido-grohmann-pforzheim-kollmar-jordan-haus-04-web.jpg\" data-src=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/guido-grohmann-pforzheim-kollmar-jordan-haus-04-web.jpg\"><div class=\"gridblock-links-wrap\"><\/div><div class=\"boxtitle-hover\"><div class=\"work-details\"><h4>Kollmar & Jordan House<\/h4><p class=\"entry-content work-description\">Pforzheim's Technical Museum of the jewelry and watch industry<\/p><\/div><\/div><\/a><\/div><img decoding=\"async\" class=\"preload-image lazyload displayed-image\" src=\"https:\/\/guidogrohmann.de\/wp-content\/themes\/blacksilver\/images\/placeholders\/placeholder-770x770.gif\" data-src=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/guido-grohmann-pforzheim-kollmar-jordan-haus-04-web-770x770.jpg\" alt=\"Kollmar & Jordan House\"><\/div><\/div><div class=\"gridblock-element  grid-animate-display-all isotope-displayed gridblock-thumbnail-id-7721 gridblock-col-1\"><div class=\"gridblock-ajax gridblock-grid-element gridblock-element-inner\" data-rel=\"7715\"><div class=\"gridblock-background-hover\"><a data-elementor-open-lightbox=\"no\" data-exthumbimage=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/germany-pforzheim-02-guido-grohmann-2020-03-160x160.jpg\" class=\"lightbox-active lightbox-image gridblock-sole-link\" data-sub-html=\"&lt;div class=&quot;lightbox-text-wrap &quot;&gt;&lt;h4 class=&quot;lightbox-text lightbox-text-title&quot;&gt;Pforzheim ZOB&lt;\/h4&gt;&lt;div class=&quot;lightbox-text entry-content&quot;&gt;Pforzheim\u2019s ZOB embodies the city\u2019s forward-looking spirit, linking local life with regional horizons.&lt;\/div&gt;&lt;\/div&gt;\" href=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/germany-pforzheim-02-guido-grohmann-2020-03.jpg\" data-src=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/germany-pforzheim-02-guido-grohmann-2020-03.jpg\"><div class=\"gridblock-links-wrap\"><\/div><div class=\"boxtitle-hover\"><div class=\"work-details\"><h4>Pforzheim ZOB<\/h4><p class=\"entry-content work-description\">Pforzheim\u2019s ZOB embodies the city\u2019s forward-looking spirit, linking local life with regional horizons.<\/p><\/div><\/div><\/a><\/div><img decoding=\"async\" class=\"preload-image lazyload displayed-image\" src=\"https:\/\/guidogrohmann.de\/wp-content\/themes\/blacksilver\/images\/placeholders\/placeholder-770x770.gif\" data-src=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/germany-pforzheim-02-guido-grohmann-2020-03-770x770.jpg\" alt=\"Pforzheim ZOB\"><\/div><\/div><div class=\"gridblock-element  grid-animate-display-all isotope-displayed gridblock-thumbnail-id-7723 gridblock-col-2\"><div class=\"gridblock-ajax gridblock-grid-element gridblock-element-inner\" data-rel=\"7715\"><div class=\"gridblock-background-hover\"><a data-elementor-open-lightbox=\"no\" data-exthumbimage=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/germany-pforzheim-03-guido-grohmann-2020-03-160x160.jpg\" class=\"lightbox-active lightbox-image gridblock-sole-link\" data-sub-html=\"&lt;div class=&quot;lightbox-text-wrap &quot;&gt;&lt;h4 class=&quot;lightbox-text lightbox-text-title&quot;&gt;Pforzheim ZOB&lt;\/h4&gt;&lt;div class=&quot;lightbox-text entry-content&quot;&gt;Functional and transparent, Pforzheim\u2019s ZOB reflects a city in motion, connecting people and places.&lt;\/div&gt;&lt;\/div&gt;\" href=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/germany-pforzheim-03-guido-grohmann-2020-03.jpg\" data-src=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/germany-pforzheim-03-guido-grohmann-2020-03.jpg\"><div class=\"gridblock-links-wrap\"><\/div><div class=\"boxtitle-hover\"><div class=\"work-details\"><h4>Pforzheim ZOB<\/h4><p class=\"entry-content work-description\">Functional and transparent, Pforzheim\u2019s ZOB reflects a city in motion, connecting people and places.<\/p><\/div><\/div><\/a><\/div><img decoding=\"async\" class=\"preload-image lazyload displayed-image\" src=\"https:\/\/guidogrohmann.de\/wp-content\/themes\/blacksilver\/images\/placeholders\/placeholder-770x770.gif\" data-src=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/germany-pforzheim-03-guido-grohmann-2020-03-770x770.jpg\" alt=\"Pforzheim ZOB\"><\/div><\/div><div class=\"gridblock-element  grid-animate-display-all isotope-displayed gridblock-thumbnail-id-7718 gridblock-col-1\"><div class=\"gridblock-ajax gridblock-grid-element gridblock-element-inner\" data-rel=\"7715\"><div class=\"gridblock-background-hover\"><a data-elementor-open-lightbox=\"no\" data-exthumbimage=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/germany-pforzheim-01-guido-grohmann-2020-03-160x160.jpg\" class=\"lightbox-active lightbox-image gridblock-sole-link\" data-sub-html=\"&lt;div class=&quot;lightbox-text-wrap &quot;&gt;&lt;h4 class=&quot;lightbox-text lightbox-text-title&quot;&gt;The Trunk&lt;\/h4&gt;&lt;div class=&quot;lightbox-text entry-content&quot;&gt;The Trunk, with its flowing brick and glass fa\u00e7ade, rises as a landmark of contemporary architecture and innovation in Pforzheim.&lt;\/div&gt;&lt;\/div&gt;\" href=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/germany-pforzheim-01-guido-grohmann-2020-03.jpg\" data-src=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/germany-pforzheim-01-guido-grohmann-2020-03.jpg\"><div class=\"gridblock-links-wrap\"><\/div><div class=\"boxtitle-hover\"><div class=\"work-details\"><h4>The Trunk<\/h4><p class=\"entry-content work-description\">The Trunk, with its flowing brick and glass fa\u00e7ade, rises as a landmark of contemporary architecture and innovation in Pforzheim.<\/p><\/div><\/div><\/a><\/div><img decoding=\"async\" class=\"preload-image lazyload displayed-image\" src=\"https:\/\/guidogrohmann.de\/wp-content\/themes\/blacksilver\/images\/placeholders\/placeholder-770x770.gif\" data-src=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/germany-pforzheim-01-guido-grohmann-2020-03-770x770.jpg\" alt=\"The Trunk\"><\/div><\/div><div class=\"gridblock-element  grid-animate-display-all isotope-displayed gridblock-thumbnail-id-7719 gridblock-col-2\"><div class=\"gridblock-ajax gridblock-grid-element gridblock-element-inner\" data-rel=\"7715\"><div class=\"gridblock-background-hover\"><a data-elementor-open-lightbox=\"no\" data-exthumbimage=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/germany-pforzheim-01-guido-grohmann-2025-06-160x160.jpg\" class=\"lightbox-active lightbox-image gridblock-sole-link\" data-sub-html=\"&lt;div class=&quot;lightbox-text-wrap &quot;&gt;&lt;h4 class=&quot;lightbox-text lightbox-text-title&quot;&gt;Applause&lt;\/h4&gt;&lt;div class=&quot;lightbox-text entry-content&quot;&gt;Guido Messer&#039;s sculpture \u201eDie Claque\u201c lines the Enz bridge with identical figures in applause.&lt;\/div&gt;&lt;\/div&gt;\" href=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/germany-pforzheim-01-guido-grohmann-2025-06.jpg\" data-src=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/germany-pforzheim-01-guido-grohmann-2025-06.jpg\"><div class=\"gridblock-links-wrap\"><\/div><div class=\"boxtitle-hover\"><div class=\"work-details\"><h4>Applause<\/h4><p class=\"entry-content work-description\">Guido Messer's sculpture \u201eDie Claque\u201c lines the Enz bridge with identical figures in applause.<\/p><\/div><\/div><\/a><\/div><img decoding=\"async\" class=\"preload-image lazyload displayed-image\" src=\"https:\/\/guidogrohmann.de\/wp-content\/themes\/blacksilver\/images\/placeholders\/placeholder-770x770.gif\" data-src=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/germany-pforzheim-01-guido-grohmann-2025-06-770x770.jpg\" alt=\"Applause\"><\/div><\/div><div class=\"gridblock-element  grid-animate-display-all isotope-displayed gridblock-thumbnail-id-7722 gridblock-col-1\"><div class=\"gridblock-ajax gridblock-grid-element gridblock-element-inner\" data-rel=\"7715\"><div class=\"gridblock-background-hover\"><a data-elementor-open-lightbox=\"no\" data-exthumbimage=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/germany-pforzheim-02-guido-grohmann-2025-06-160x160.jpg\" class=\"lightbox-active lightbox-image gridblock-sole-link\" data-sub-html=\"&lt;div class=&quot;lightbox-text-wrap &quot;&gt;&lt;h4 class=&quot;lightbox-text lightbox-text-title&quot;&gt;Auerbr\u00fccke&lt;\/h4&gt;&lt;div class=&quot;lightbox-text entry-content&quot;&gt;The Auer Bridge, crowned by the Fl\u00f6\u00dfer monument at its center, recalls Pforzheim\u2019s river heritage where timber once journeyed from the Black Forest to the world.&lt;\/div&gt;&lt;\/div&gt;\" href=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/germany-pforzheim-02-guido-grohmann-2025-06.jpg\" data-src=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/germany-pforzheim-02-guido-grohmann-2025-06.jpg\"><div class=\"gridblock-links-wrap\"><\/div><div class=\"boxtitle-hover\"><div class=\"work-details\"><h4>Auerbr\u00fccke<\/h4><p class=\"entry-content work-description\">The Auer Bridge, crowned by the Fl\u00f6\u00dfer monument at its center, recalls Pforzheim\u2019s river heritage where timber once journeyed from the Black Forest to the world.<\/p><\/div><\/div><\/a><\/div><img decoding=\"async\" class=\"preload-image lazyload displayed-image\" src=\"https:\/\/guidogrohmann.de\/wp-content\/themes\/blacksilver\/images\/placeholders\/placeholder-770x770.gif\" data-src=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/germany-pforzheim-02-guido-grohmann-2025-06-770x770.jpg\" alt=\"Auerbr\u00fccke\"><\/div><\/div><div class=\"gridblock-element  grid-animate-display-all isotope-displayed gridblock-thumbnail-id-8397 gridblock-col-2\"><div class=\"gridblock-ajax gridblock-grid-element gridblock-element-inner\" data-rel=\"7715\"><div class=\"gridblock-background-hover\"><a data-elementor-open-lightbox=\"no\" data-exthumbimage=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/20250920-guido-grohmann-pforzheim-04-160x160.jpg\" class=\"lightbox-active lightbox-image gridblock-sole-link\" data-sub-html=\"&lt;div class=&quot;lightbox-text-wrap &quot;&gt;&lt;h4 class=&quot;lightbox-text lightbox-text-title&quot;&gt;Sunrise in September&lt;\/h4&gt;&lt;div class=&quot;lightbox-text entry-content&quot;&gt;Pforzheim City looking East&lt;\/div&gt;&lt;\/div&gt;\" href=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/20250920-guido-grohmann-pforzheim-04.jpg\" data-src=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/20250920-guido-grohmann-pforzheim-04.jpg\"><div class=\"gridblock-links-wrap\"><\/div><div class=\"boxtitle-hover\"><div class=\"work-details\"><h4>Sunrise in September<\/h4><p class=\"entry-content work-description\">Pforzheim City looking East<\/p><\/div><\/div><\/a><\/div><img decoding=\"async\" class=\"preload-image lazyload displayed-image\" src=\"https:\/\/guidogrohmann.de\/wp-content\/themes\/blacksilver\/images\/placeholders\/placeholder-770x770.gif\" data-src=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/20250920-guido-grohmann-pforzheim-04-770x770.jpg\" alt=\"Sunrise in September\"><\/div><\/div><div class=\"gridblock-element  grid-animate-display-all isotope-displayed gridblock-thumbnail-id-7724 gridblock-col-1\"><div class=\"gridblock-ajax gridblock-grid-element gridblock-element-inner\" data-rel=\"7715\"><div class=\"gridblock-background-hover\"><a data-elementor-open-lightbox=\"no\" data-exthumbimage=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/germany-pforzheim-03-guido-grohmann-2025-06-160x160.jpg\" class=\"lightbox-active lightbox-image gridblock-sole-link\" data-sub-html=\"&lt;div class=&quot;lightbox-text-wrap &quot;&gt;&lt;h4 class=&quot;lightbox-text lightbox-text-title&quot;&gt;Parkhotel and Church&lt;\/h4&gt;&lt;div class=&quot;lightbox-text entry-content&quot;&gt;The Parkhotel and its adjoining church form a dialogue of stone and glass, hospitality and faith.&lt;\/div&gt;&lt;\/div&gt;\" href=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/germany-pforzheim-03-guido-grohmann-2025-06.jpg\" data-src=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/germany-pforzheim-03-guido-grohmann-2025-06.jpg\"><div class=\"gridblock-links-wrap\"><\/div><div class=\"boxtitle-hover\"><div class=\"work-details\"><h4>Parkhotel and Church<\/h4><p class=\"entry-content work-description\">The Parkhotel and its adjoining church form a dialogue of stone and glass, hospitality and faith.<\/p><\/div><\/div><\/a><\/div><img decoding=\"async\" class=\"preload-image lazyload displayed-image\" src=\"https:\/\/guidogrohmann.de\/wp-content\/themes\/blacksilver\/images\/placeholders\/placeholder-770x770.gif\" data-src=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/germany-pforzheim-03-guido-grohmann-2025-06-770x770.jpg\" alt=\"Parkhotel and Church\"><\/div><\/div><div class=\"gridblock-element  grid-animate-display-all isotope-displayed gridblock-thumbnail-id-7725 gridblock-col-2\"><div class=\"gridblock-ajax gridblock-grid-element gridblock-element-inner\" data-rel=\"7715\"><div class=\"gridblock-background-hover\"><a data-elementor-open-lightbox=\"no\" data-exthumbimage=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/germany-pforzheim-04-guido-grohmann-2020-03-160x160.jpg\" class=\"lightbox-active lightbox-image gridblock-sole-link\" data-sub-html=\"&lt;div class=&quot;lightbox-text-wrap &quot;&gt;&lt;h4 class=&quot;lightbox-text lightbox-text-title&quot;&gt;Pforzheim Train Station&lt;\/h4&gt;&lt;div class=&quot;lightbox-text entry-content&quot;&gt;Pforzheim\u2019s Hauptbahnhof, modern in form, recalls the days when the city\u2019s jewelry set out from here to adorn the world.&lt;\/div&gt;&lt;\/div&gt;\" href=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/germany-pforzheim-04-guido-grohmann-2020-03.jpg\" data-src=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/germany-pforzheim-04-guido-grohmann-2020-03.jpg\"><div class=\"gridblock-links-wrap\"><\/div><div class=\"boxtitle-hover\"><div class=\"work-details\"><h4>Pforzheim Train Station<\/h4><p class=\"entry-content work-description\">Pforzheim\u2019s Hauptbahnhof, modern in form, recalls the days when the city\u2019s jewelry set out from here to adorn the world.<\/p><\/div><\/div><\/a><\/div><img decoding=\"async\" class=\"preload-image lazyload displayed-image\" src=\"https:\/\/guidogrohmann.de\/wp-content\/themes\/blacksilver\/images\/placeholders\/placeholder-770x770.gif\" data-src=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/germany-pforzheim-04-guido-grohmann-2020-03-770x770.jpg\" alt=\"Pforzheim Train Station\"><\/div><\/div><div class=\"gridblock-element  grid-animate-display-all isotope-displayed gridblock-thumbnail-id-7726 gridblock-col-1\"><div class=\"gridblock-ajax gridblock-grid-element gridblock-element-inner\" data-rel=\"7715\"><div class=\"gridblock-background-hover\"><a data-elementor-open-lightbox=\"no\" data-exthumbimage=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/germany-pforzheim-04-guido-grohmann-2025-06-160x160.jpg\" class=\"lightbox-active lightbox-image gridblock-sole-link\" data-sub-html=\"&lt;div class=&quot;lightbox-text-wrap &quot;&gt;&lt;h4 class=&quot;lightbox-text lightbox-text-title&quot;&gt;Gernika Bridge&lt;\/h4&gt;&lt;div class=&quot;lightbox-text entry-content&quot;&gt;Shaped like a goldsmith\u2019s tool, the Gernika Bridge celebrates Pforzheim\u2019s bond with its Basque twin city.&lt;\/div&gt;&lt;\/div&gt;\" href=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/germany-pforzheim-04-guido-grohmann-2025-06.jpg\" data-src=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/germany-pforzheim-04-guido-grohmann-2025-06.jpg\"><div class=\"gridblock-links-wrap\"><\/div><div class=\"boxtitle-hover\"><div class=\"work-details\"><h4>Gernika Bridge<\/h4><p class=\"entry-content work-description\">Shaped like a goldsmith\u2019s tool, the Gernika Bridge celebrates Pforzheim\u2019s bond with its Basque twin city.<\/p><\/div><\/div><\/a><\/div><img decoding=\"async\" class=\"preload-image lazyload displayed-image\" src=\"https:\/\/guidogrohmann.de\/wp-content\/themes\/blacksilver\/images\/placeholders\/placeholder-770x770.gif\" data-src=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/germany-pforzheim-04-guido-grohmann-2025-06-770x770.jpg\" alt=\"Gernika Bridge\"><\/div><\/div><div class=\"gridblock-element  grid-animate-display-all isotope-displayed gridblock-thumbnail-id-7727 gridblock-col-2\"><div class=\"gridblock-ajax gridblock-grid-element gridblock-element-inner\" data-rel=\"7715\"><div class=\"gridblock-background-hover\"><a data-elementor-open-lightbox=\"no\" data-exthumbimage=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/germany-pforzheim-05-guido-grohmann-2025-06-160x160.jpg\" class=\"lightbox-active lightbox-image gridblock-sole-link\" data-sub-html=\"&lt;div class=&quot;lightbox-text-wrap &quot;&gt;&lt;h4 class=&quot;lightbox-text lightbox-text-title&quot;&gt;Bertha Benz Monument&lt;\/h4&gt;&lt;div class=&quot;lightbox-text entry-content&quot;&gt;The Bertha Benz Monument honors the woman whose pioneering drive from Mannheim to Pforzheim marked the dawn of modern mobility.&lt;\/div&gt;&lt;\/div&gt;\" href=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/germany-pforzheim-05-guido-grohmann-2025-06.jpg\" data-src=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/germany-pforzheim-05-guido-grohmann-2025-06.jpg\"><div class=\"gridblock-links-wrap\"><\/div><div class=\"boxtitle-hover\"><div class=\"work-details\"><h4>Bertha Benz Monument<\/h4><p class=\"entry-content work-description\">The Bertha Benz Monument honors the woman whose pioneering drive from Mannheim to Pforzheim marked the dawn of modern mobility.<\/p><\/div><\/div><\/a><\/div><img decoding=\"async\" class=\"preload-image lazyload displayed-image\" src=\"https:\/\/guidogrohmann.de\/wp-content\/themes\/blacksilver\/images\/placeholders\/placeholder-770x770.gif\" data-src=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/germany-pforzheim-05-guido-grohmann-2025-06-770x770.jpg\" alt=\"Bertha Benz Monument\"><\/div><\/div><div class=\"gridblock-element  grid-animate-display-all isotope-displayed gridblock-thumbnail-id-7728 gridblock-col-1\"><div class=\"gridblock-ajax gridblock-grid-element gridblock-element-inner\" data-rel=\"7715\"><div class=\"gridblock-background-hover\"><a data-elementor-open-lightbox=\"no\" data-exthumbimage=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/germany-pforzheim-06-guido-grohmann-2020-03-160x160.jpg\" class=\"lightbox-active lightbox-image gridblock-sole-link\" data-sub-html=\"&lt;div class=&quot;lightbox-text-wrap &quot;&gt;&lt;h4 class=&quot;lightbox-text lightbox-text-title&quot;&gt;Westliche KF&lt;\/h4&gt;&lt;div class=&quot;lightbox-text entry-content&quot;&gt;The Westliche Karl-Friedrich-Stra\u00dfe stretches like Pforzheim\u2019s urban spine \u2013 rebuilt in concrete clarity, yet alive with the pulse of the city.&lt;\/div&gt;&lt;\/div&gt;\" href=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/germany-pforzheim-06-guido-grohmann-2020-03.jpg\" data-src=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/germany-pforzheim-06-guido-grohmann-2020-03.jpg\"><div class=\"gridblock-links-wrap\"><\/div><div class=\"boxtitle-hover\"><div class=\"work-details\"><h4>Westliche KF<\/h4><p class=\"entry-content work-description\">The Westliche Karl-Friedrich-Stra\u00dfe stretches like Pforzheim\u2019s urban spine \u2013 rebuilt in concrete clarity, yet alive with the pulse of the city.<\/p><\/div><\/div><\/a><\/div><img decoding=\"async\" class=\"preload-image lazyload displayed-image\" src=\"https:\/\/guidogrohmann.de\/wp-content\/themes\/blacksilver\/images\/placeholders\/placeholder-770x770.gif\" data-src=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/germany-pforzheim-06-guido-grohmann-2020-03-770x770.jpg\" alt=\"Westliche KF\"><\/div><\/div><div class=\"gridblock-element  grid-animate-display-all isotope-displayed gridblock-thumbnail-id-7729 gridblock-col-2\"><div class=\"gridblock-ajax gridblock-grid-element gridblock-element-inner\" data-rel=\"7715\"><div class=\"gridblock-background-hover\"><a data-elementor-open-lightbox=\"no\" data-exthumbimage=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/germany-pforzheim-06-guido-grohmann-2025-06-160x160.jpg\" class=\"lightbox-active lightbox-image gridblock-sole-link\" data-sub-html=\"&lt;div class=&quot;lightbox-text-wrap &quot;&gt;&lt;h4 class=&quot;lightbox-text lightbox-text-title&quot;&gt;Pforzheim Town Hall&lt;\/h4&gt;&lt;div class=&quot;lightbox-text entry-content&quot;&gt;Pforzheim\u2019s Town Hall rises in sober post-war modernism, a symbol of civic renewal after devastation.&lt;\/div&gt;&lt;\/div&gt;\" href=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/germany-pforzheim-06-guido-grohmann-2025-06.jpg\" data-src=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/germany-pforzheim-06-guido-grohmann-2025-06.jpg\"><div class=\"gridblock-links-wrap\"><\/div><div class=\"boxtitle-hover\"><div class=\"work-details\"><h4>Pforzheim Town Hall<\/h4><p class=\"entry-content work-description\">Pforzheim\u2019s Town Hall rises in sober post-war modernism, a symbol of civic renewal after devastation.<\/p><\/div><\/div><\/a><\/div><img decoding=\"async\" class=\"preload-image lazyload displayed-image\" src=\"https:\/\/guidogrohmann.de\/wp-content\/themes\/blacksilver\/images\/placeholders\/placeholder-770x770.gif\" data-src=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/germany-pforzheim-06-guido-grohmann-2025-06-770x770.jpg\" alt=\"Pforzheim Town Hall\"><\/div><\/div><div class=\"gridblock-element  grid-animate-display-all isotope-displayed gridblock-thumbnail-id-7731 gridblock-col-1\"><div class=\"gridblock-ajax gridblock-grid-element gridblock-element-inner\" data-rel=\"7715\"><div class=\"gridblock-background-hover\"><a data-elementor-open-lightbox=\"no\" data-exthumbimage=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/germany-pforzheim-waisenhausplatz-guido-grohmann-2025-06-160x160.jpg\" class=\"lightbox-active lightbox-image gridblock-sole-link\" data-sub-html=\"&lt;div class=&quot;lightbox-text-wrap &quot;&gt;&lt;h4 class=&quot;lightbox-text lightbox-text-title&quot;&gt;Waisenhausplatz&lt;\/h4&gt;&lt;div class=&quot;lightbox-text entry-content&quot;&gt;Waisenhausplatz tells of origins and absence \u2013 the cradle of jewelry craftsmanship and a reminder of what vanished.&lt;\/div&gt;&lt;\/div&gt;\" href=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/germany-pforzheim-waisenhausplatz-guido-grohmann-2025-06.jpg\" data-src=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/germany-pforzheim-waisenhausplatz-guido-grohmann-2025-06.jpg\"><div class=\"gridblock-links-wrap\"><\/div><div class=\"boxtitle-hover\"><div class=\"work-details\"><h4>Waisenhausplatz<\/h4><p class=\"entry-content work-description\">Waisenhausplatz tells of origins and absence \u2013 the cradle of jewelry craftsmanship and a reminder of what vanished.<\/p><\/div><\/div><\/a><\/div><img decoding=\"async\" class=\"preload-image lazyload displayed-image\" src=\"https:\/\/guidogrohmann.de\/wp-content\/themes\/blacksilver\/images\/placeholders\/placeholder-770x770.gif\" data-src=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/germany-pforzheim-waisenhausplatz-guido-grohmann-2025-06-770x770.jpg\" alt=\"Waisenhausplatz\"><\/div><\/div><div class=\"gridblock-element  grid-animate-display-all isotope-displayed gridblock-thumbnail-id-7732 gridblock-col-2\"><div class=\"gridblock-ajax gridblock-grid-element gridblock-element-inner\" data-rel=\"7715\"><div class=\"gridblock-background-hover\"><a data-elementor-open-lightbox=\"no\" data-exthumbimage=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/germany-pforzheim-wallberg-01-guido-grohmann-2020-03-160x160.jpg\" class=\"lightbox-active lightbox-image gridblock-sole-link\" data-sub-html=\"&lt;div class=&quot;lightbox-text-wrap &quot;&gt;&lt;h4 class=&quot;lightbox-text lightbox-text-title&quot;&gt;Wallberg&lt;\/h4&gt;&lt;div class=&quot;lightbox-text entry-content&quot;&gt;The Wallberg stands as a silent witness to Pforzheim\u2019s destruction and rebirth.&lt;\/div&gt;&lt;\/div&gt;\" href=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/germany-pforzheim-wallberg-01-guido-grohmann-2020-03.jpg\" data-src=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/germany-pforzheim-wallberg-01-guido-grohmann-2020-03.jpg\"><div class=\"gridblock-links-wrap\"><\/div><div class=\"boxtitle-hover\"><div class=\"work-details\"><h4>Wallberg<\/h4><p class=\"entry-content work-description\">The Wallberg stands as a silent witness to Pforzheim\u2019s destruction and rebirth.<\/p><\/div><\/div><\/a><\/div><img decoding=\"async\" class=\"preload-image lazyload displayed-image\" src=\"https:\/\/guidogrohmann.de\/wp-content\/themes\/blacksilver\/images\/placeholders\/placeholder-770x770.gif\" data-src=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/germany-pforzheim-wallberg-01-guido-grohmann-2020-03-770x770.jpg\" alt=\"Wallberg\"><\/div><\/div><div class=\"gridblock-element  grid-animate-display-all isotope-displayed gridblock-thumbnail-id-8399 gridblock-col-1\"><div class=\"gridblock-ajax gridblock-grid-element gridblock-element-inner\" data-rel=\"7715\"><div class=\"gridblock-background-hover\"><a data-elementor-open-lightbox=\"no\" data-exthumbimage=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/20250920-guido-grohmann-pforzheim-03-160x160.jpg\" class=\"lightbox-active lightbox-image gridblock-sole-link\" data-sub-html=\"&lt;div class=&quot;lightbox-text-wrap &quot;&gt;&lt;h4 class=&quot;lightbox-text lightbox-text-title&quot;&gt;Pforzheim City&lt;\/h4&gt;&lt;div class=&quot;lightbox-text entry-content&quot;&gt;Before Pforzheim wakes up&lt;\/div&gt;&lt;\/div&gt;\" href=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/20250920-guido-grohmann-pforzheim-03.jpg\" data-src=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/20250920-guido-grohmann-pforzheim-03.jpg\"><div class=\"gridblock-links-wrap\"><\/div><div class=\"boxtitle-hover\"><div class=\"work-details\"><h4>Pforzheim City<\/h4><p class=\"entry-content work-description\">Before Pforzheim wakes up<\/p><\/div><\/div><\/a><\/div><img decoding=\"async\" class=\"preload-image lazyload displayed-image\" src=\"https:\/\/guidogrohmann.de\/wp-content\/themes\/blacksilver\/images\/placeholders\/placeholder-770x770.gif\" data-src=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/20250920-guido-grohmann-pforzheim-03-770x770.jpg\" alt=\"Pforzheim City\"><\/div><\/div><div class=\"gridblock-element  grid-animate-display-all isotope-displayed gridblock-thumbnail-id-8400 gridblock-col-2\"><div class=\"gridblock-ajax gridblock-grid-element gridblock-element-inner\" data-rel=\"7715\"><div class=\"gridblock-background-hover\"><a data-elementor-open-lightbox=\"no\" data-exthumbimage=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/20250920-guido-grohmann-pforzheim-02-160x160.jpg\" class=\"lightbox-active lightbox-image gridblock-sole-link\" data-sub-html=\"&lt;div class=&quot;lightbox-text-wrap &quot;&gt;&lt;h4 class=&quot;lightbox-text lightbox-text-title&quot;&gt;Pforzheim City&lt;\/h4&gt;&lt;div class=&quot;lightbox-text entry-content&quot;&gt;Before Pforzheim wakes up&lt;\/div&gt;&lt;\/div&gt;\" href=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/20250920-guido-grohmann-pforzheim-02.jpg\" data-src=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/20250920-guido-grohmann-pforzheim-02.jpg\"><div class=\"gridblock-links-wrap\"><\/div><div class=\"boxtitle-hover\"><div class=\"work-details\"><h4>Pforzheim City<\/h4><p class=\"entry-content work-description\">Before Pforzheim wakes up<\/p><\/div><\/div><\/a><\/div><img decoding=\"async\" class=\"preload-image lazyload displayed-image\" src=\"https:\/\/guidogrohmann.de\/wp-content\/themes\/blacksilver\/images\/placeholders\/placeholder-770x770.gif\" data-src=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/20250920-guido-grohmann-pforzheim-02-770x770.jpg\" alt=\"Pforzheim City\"><\/div><\/div><div class=\"gridblock-element  grid-animate-display-all isotope-displayed gridblock-thumbnail-id-8403 gridblock-col-1\"><div class=\"gridblock-ajax gridblock-grid-element gridblock-element-inner\" data-rel=\"7715\"><div class=\"gridblock-background-hover\"><a data-elementor-open-lightbox=\"no\" data-exthumbimage=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/20250920-guido-grohmann-pforzheim-bahnhof-01-160x160.jpg\" class=\"lightbox-active lightbox-image gridblock-sole-link\" data-sub-html=\"&lt;div class=&quot;lightbox-text-wrap &quot;&gt;&lt;h4 class=&quot;lightbox-text lightbox-text-title&quot;&gt;Pforzheim Train Station&lt;\/h4&gt;&lt;div class=&quot;lightbox-text entry-content&quot;&gt;Pforzheim\u2019s Hauptbahnhof, modern in form, recalls the days when the city\u2019s jewelry set out from here to adorn the world.&lt;\/div&gt;&lt;\/div&gt;\" href=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/20250920-guido-grohmann-pforzheim-bahnhof-01.jpg\" data-src=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/20250920-guido-grohmann-pforzheim-bahnhof-01.jpg\"><div class=\"gridblock-links-wrap\"><\/div><div class=\"boxtitle-hover\"><div class=\"work-details\"><h4>Pforzheim Train Station<\/h4><p class=\"entry-content work-description\">Pforzheim\u2019s Hauptbahnhof, modern in form, recalls the days when the city\u2019s jewelry set out from here to adorn the world.<\/p><\/div><\/div><\/a><\/div><img decoding=\"async\" class=\"preload-image lazyload displayed-image\" src=\"https:\/\/guidogrohmann.de\/wp-content\/themes\/blacksilver\/images\/placeholders\/placeholder-770x770.gif\" data-src=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/20250920-guido-grohmann-pforzheim-bahnhof-01-770x770.jpg\" alt=\"Pforzheim Train Station\"><\/div><\/div><div class=\"gridblock-element  grid-animate-display-all isotope-displayed gridblock-thumbnail-id-7730 gridblock-col-2\"><div class=\"gridblock-ajax gridblock-grid-element gridblock-element-inner\" data-rel=\"7715\"><div class=\"gridblock-background-hover\"><a data-elementor-open-lightbox=\"no\" data-exthumbimage=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/germany-pforzheim-dillweissenstein-guido-grohmann-2025-06-160x160.jpg\" class=\"lightbox-active lightbox-image gridblock-sole-link\" data-sub-html=\"&lt;div class=&quot;lightbox-text-wrap &quot;&gt;&lt;h4 class=&quot;lightbox-text lightbox-text-title&quot;&gt;Dillweissenstein Bridge&lt;\/h4&gt;&lt;div class=&quot;lightbox-text entry-content&quot;&gt;The Dillwei\u00dfenstein Bridge stands as a quiet link between Pforzheim\u2019s heritage and its ever-changing present.&lt;\/div&gt;&lt;\/div&gt;\" href=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/germany-pforzheim-dillweissenstein-guido-grohmann-2025-06.jpg\" data-src=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/germany-pforzheim-dillweissenstein-guido-grohmann-2025-06.jpg\"><div class=\"gridblock-links-wrap\"><\/div><div class=\"boxtitle-hover\"><div class=\"work-details\"><h4>Dillweissenstein Bridge<\/h4><p class=\"entry-content work-description\">The Dillwei\u00dfenstein Bridge stands as a quiet link between Pforzheim\u2019s heritage and its ever-changing present.<\/p><\/div><\/div><\/a><\/div><img decoding=\"async\" class=\"preload-image lazyload displayed-image\" src=\"https:\/\/guidogrohmann.de\/wp-content\/themes\/blacksilver\/images\/placeholders\/placeholder-770x770.gif\" data-src=\"https:\/\/guidogrohmann.de\/wp-content\/uploads\/2025\/09\/germany-pforzheim-dillweissenstein-guido-grohmann-2025-06-770x770.jpg\" alt=\"Dillweissenstein Bridge\"><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Gallery Pforzheim Pforzheim ist ein Ort, an dem sich die raue Atmosph\u00e4re der Nachkriegszeit, jahrhunderte altes Schmuckhandwerk und die Zeitlosigkeit des Schwarzwaldes miteinander verbinden. Wallberg The Wallberg stands as a silent witness to Pforzheim\u2019s destruction and rebirth. Wallberg The Wallberg stands as a silent witness to Pforzheim\u2019s destruction and rebirth. Wallberg The Wallberg stands as a silent witness to Pforzheim\u2019s destruction and rebirth. Wallberg The Wallberg stands as a silent witness to Pforzheim\u2019s destruction and rebirth. Hafnerwiesen The Hafnerwiesen unfold [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"parent":7822,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-7715","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pforzheim - Guido Grohmann Photography<\/title>\n<meta name=\"description\" content=\"Pforzheim ist ein Ort, an dem sich die Atmosph\u00e4re der Nachkriegszeit, altes Schmuckhandwerk und die Sch\u00f6nheit des Schwarzwaldes verbinden.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/guidogrohmann.de\/en\/guido-galleries\/pforzheim-gallery\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pforzheim - Guido Grohmann Photography\" \/>\n<meta property=\"og:description\" content=\"Pforzheim ist ein Ort, an dem sich die Atmosph\u00e4re der Nachkriegszeit, altes Schmuckhandwerk und die Sch\u00f6nheit des Schwarzwaldes verbinden.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/guidogrohmann.de\/en\/guido-galleries\/pforzheim-gallery\/\" \/>\n<meta property=\"og:site_name\" content=\"Guido Grohmann Photography\" \/>\n<meta property=\"article:publisher\" content=\"facebook.com\/guido.grohmann\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-09T07:36:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/guidogrohmann.de\/wp-content\/themes\/blacksilver\/images\/placeholders\/placeholder-770x770.gif\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"11 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\/\/guidogrohmann.de\/guido-galleries\/pforzheim-gallery\/\",\"url\":\"http:\/\/guidogrohmann.de\/guido-galleries\/pforzheim-gallery\/\",\"name\":\"Pforzheim - Guido Grohmann Photography\",\"isPartOf\":{\"@id\":\"http:\/\/guidogrohmann.de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/guidogrohmann.de\/guido-galleries\/pforzheim-gallery\/#primaryimage\"},\"image\":{\"@id\":\"http:\/\/guidogrohmann.de\/guido-galleries\/pforzheim-gallery\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/guidogrohmann.de\/wp-content\/themes\/blacksilver\/images\/placeholders\/placeholder-770x770.gif\",\"datePublished\":\"2025-09-11T16:48:39+00:00\",\"dateModified\":\"2025-10-09T07:36:05+00:00\",\"description\":\"Pforzheim ist ein Ort, an dem sich die Atmosph\u00e4re der Nachkriegszeit, altes Schmuckhandwerk und die Sch\u00f6nheit des Schwarzwaldes verbinden.\",\"breadcrumb\":{\"@id\":\"http:\/\/guidogrohmann.de\/guido-galleries\/pforzheim-gallery\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/guidogrohmann.de\/guido-galleries\/pforzheim-gallery\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\/\/guidogrohmann.de\/guido-galleries\/pforzheim-gallery\/#primaryimage\",\"url\":\"https:\/\/guidogrohmann.de\/wp-content\/themes\/blacksilver\/images\/placeholders\/placeholder-770x770.gif\",\"contentUrl\":\"https:\/\/guidogrohmann.de\/wp-content\/themes\/blacksilver\/images\/placeholders\/placeholder-770x770.gif\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/guidogrohmann.de\/guido-galleries\/pforzheim-gallery\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"http:\/\/guidogrohmann.de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Guido Galleries\",\"item\":\"http:\/\/guidogrohmann.de\/guido-galleries\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Pforzheim\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/guidogrohmann.de\/#website\",\"url\":\"http:\/\/guidogrohmann.de\/\",\"name\":\"Guido Grohmann Photography\",\"description\":\"\",\"publisher\":{\"@id\":\"http:\/\/guidogrohmann.de\/#\/schema\/person\/fc6a193814ea2f3a6b7d0c9caf89b5ec\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/guidogrohmann.de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"http:\/\/guidogrohmann.de\/#\/schema\/person\/fc6a193814ea2f3a6b7d0c9caf89b5ec\",\"name\":\"Guido Grohmann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\/\/guidogrohmann.de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1f07fd88b8041a279426fb7b69561c2e56cfca3dcc19915a3bb33be6899f5b7c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1f07fd88b8041a279426fb7b69561c2e56cfca3dcc19915a3bb33be6899f5b7c?s=96&d=mm&r=g\",\"caption\":\"Guido Grohmann\"},\"logo\":{\"@id\":\"http:\/\/guidogrohmann.de\/#\/schema\/person\/image\/\"},\"sameAs\":[\"http:\/\/guidogrohmann.de\",\"facebook.com\/guido.grohmann\",\"https:\/\/www.instagram.com\/guidogrohmann\/\",\"https:\/\/www.linkedin.com\/in\/guido-grohmann-aa203153\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pforzheim - Guido Grohmann Photography","description":"Pforzheim ist ein Ort, an dem sich die Atmosph\u00e4re der Nachkriegszeit, altes Schmuckhandwerk und die Sch\u00f6nheit des Schwarzwaldes verbinden.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/guidogrohmann.de\/en\/guido-galleries\/pforzheim-gallery\/","og_locale":"en_US","og_type":"article","og_title":"Pforzheim - Guido Grohmann Photography","og_description":"Pforzheim ist ein Ort, an dem sich die Atmosph\u00e4re der Nachkriegszeit, altes Schmuckhandwerk und die Sch\u00f6nheit des Schwarzwaldes verbinden.","og_url":"http:\/\/guidogrohmann.de\/en\/guido-galleries\/pforzheim-gallery\/","og_site_name":"Guido Grohmann Photography","article_publisher":"facebook.com\/guido.grohmann","article_modified_time":"2025-10-09T07:36:05+00:00","og_image":[{"url":"https:\/\/guidogrohmann.de\/wp-content\/themes\/blacksilver\/images\/placeholders\/placeholder-770x770.gif","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"11 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/guidogrohmann.de\/guido-galleries\/pforzheim-gallery\/","url":"http:\/\/guidogrohmann.de\/guido-galleries\/pforzheim-gallery\/","name":"Pforzheim - Guido Grohmann Photography","isPartOf":{"@id":"http:\/\/guidogrohmann.de\/#website"},"primaryImageOfPage":{"@id":"http:\/\/guidogrohmann.de\/guido-galleries\/pforzheim-gallery\/#primaryimage"},"image":{"@id":"http:\/\/guidogrohmann.de\/guido-galleries\/pforzheim-gallery\/#primaryimage"},"thumbnailUrl":"https:\/\/guidogrohmann.de\/wp-content\/themes\/blacksilver\/images\/placeholders\/placeholder-770x770.gif","datePublished":"2025-09-11T16:48:39+00:00","dateModified":"2025-10-09T07:36:05+00:00","description":"Pforzheim ist ein Ort, an dem sich die Atmosph\u00e4re der Nachkriegszeit, altes Schmuckhandwerk und die Sch\u00f6nheit des Schwarzwaldes verbinden.","breadcrumb":{"@id":"http:\/\/guidogrohmann.de\/guido-galleries\/pforzheim-gallery\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["http:\/\/guidogrohmann.de\/guido-galleries\/pforzheim-gallery\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/guidogrohmann.de\/guido-galleries\/pforzheim-gallery\/#primaryimage","url":"https:\/\/guidogrohmann.de\/wp-content\/themes\/blacksilver\/images\/placeholders\/placeholder-770x770.gif","contentUrl":"https:\/\/guidogrohmann.de\/wp-content\/themes\/blacksilver\/images\/placeholders\/placeholder-770x770.gif"},{"@type":"BreadcrumbList","@id":"http:\/\/guidogrohmann.de\/guido-galleries\/pforzheim-gallery\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"http:\/\/guidogrohmann.de\/"},{"@type":"ListItem","position":2,"name":"Guido Galleries","item":"http:\/\/guidogrohmann.de\/guido-galleries\/"},{"@type":"ListItem","position":3,"name":"Pforzheim"}]},{"@type":"WebSite","@id":"http:\/\/guidogrohmann.de\/#website","url":"http:\/\/guidogrohmann.de\/","name":"Guido Grohmann Photography","description":"","publisher":{"@id":"http:\/\/guidogrohmann.de\/#\/schema\/person\/fc6a193814ea2f3a6b7d0c9caf89b5ec"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/guidogrohmann.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"http:\/\/guidogrohmann.de\/#\/schema\/person\/fc6a193814ea2f3a6b7d0c9caf89b5ec","name":"Guido Grohmann","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/guidogrohmann.de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1f07fd88b8041a279426fb7b69561c2e56cfca3dcc19915a3bb33be6899f5b7c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1f07fd88b8041a279426fb7b69561c2e56cfca3dcc19915a3bb33be6899f5b7c?s=96&d=mm&r=g","caption":"Guido Grohmann"},"logo":{"@id":"http:\/\/guidogrohmann.de\/#\/schema\/person\/image\/"},"sameAs":["http:\/\/guidogrohmann.de","facebook.com\/guido.grohmann","https:\/\/www.instagram.com\/guidogrohmann\/","https:\/\/www.linkedin.com\/in\/guido-grohmann-aa203153\/"]}]}},"_links":{"self":[{"href":"https:\/\/guidogrohmann.de\/en\/wp-json\/wp\/v2\/pages\/7715","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/guidogrohmann.de\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/guidogrohmann.de\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/guidogrohmann.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/guidogrohmann.de\/en\/wp-json\/wp\/v2\/comments?post=7715"}],"version-history":[{"count":28,"href":"https:\/\/guidogrohmann.de\/en\/wp-json\/wp\/v2\/pages\/7715\/revisions"}],"predecessor-version":[{"id":8631,"href":"https:\/\/guidogrohmann.de\/en\/wp-json\/wp\/v2\/pages\/7715\/revisions\/8631"}],"up":[{"embeddable":true,"href":"https:\/\/guidogrohmann.de\/en\/wp-json\/wp\/v2\/pages\/7822"}],"wp:attachment":[{"href":"https:\/\/guidogrohmann.de\/en\/wp-json\/wp\/v2\/media?parent=7715"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}